{"id":42033,"date":"2026-07-14T19:38:07","date_gmt":"2026-07-15T01:38:07","guid":{"rendered":"https:\/\/digitalreportmx.com\/?p=42033"},"modified":"2026-07-14T19:38:08","modified_gmt":"2026-07-15T01:38:08","slug":"anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon","status":"publish","type":"post","link":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/14\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\/","title":{"rendered":"ANAC se une al reclamo: exigen dinero a Nuevo Le\u00f3n"},"content":{"rendered":"\n<p><kbd>Monterrey, NL <\/kbd><\/p>\n\n\n\n<p>El presidente de la Asociaci\u00f3n Nacional de Alcaldes (ANAC M\u00e9xico) y tambi\u00e9n alcalde de Miguel Hidalgo, en la Ciudad de M\u00e9xico, Mauricio Tabe Echartea, se sum\u00f3 al pedido de 18 de sus hom\u00f3logos en esta entidad, para que se transfieran m\u00e1s de mil 700 millones de pesos que se adeudan a los municipios.<\/p>\n\n\n\n<p>A trav\u00e9s de sus redes sociales, Tabe Echartea pidi\u00f3 al Estado liberar \u201cde una vez por todas\u201d los recursos retenidos.<\/p>\n\n\n\n<p>El edil se\u00f1al\u00f3 que la entrega del dinero no puede estar sujeta a intereses ajenos al servicio p\u00fablico.<\/p>\n\n\n\n<p>\u201cNo se vale que por diferencias pol\u00edticas entre el gobernador y los presidentes municipales les retengan el recurso. No es a capricho del gobernador entregar los recursos.<\/p>\n\n\n\n\n\n<p>\u201cEs una obligaci\u00f3n por ley, porque no es su dinero, no es el dinero de los gobernantes, es el dinero de la gente y con eso a quien est\u00e1n afectando es a los habitantes de Nuevo Le\u00f3n\u201d, enfatiz\u00f3.<\/p>\n\n\n\n<p>Fue el pasado lunes cuando el alcalde de Monterrey, Adri\u00e1n de la Garza, junto con otros mun\u00edcipes de la zona metropolitana y citr\u00edcola, acudi\u00f3 al Palacio de Gobierno para solicitar el pago inmediato de estos derechos.<\/p>\n\n\n\n<p>En el lugar entregaron un documento en el que exigen el cumplimiento de la ley y la transferencia inmediata de los fondos que corresponden a cada localidad.<\/p>\n\n\n\n<p>De la Garza record\u00f3 que la falta de pago de las aportaciones afecta la prestaci\u00f3n de servicios p\u00fablicos, seguridad, e infraestructura.<\/p>\n\n\n\n<p>Instagram: https:\/\/www.instagram.com\/reel\/DaydOcVvS91\/?igsh=MWk4azQxb3V0cXNmZg==<\/p>\n\n\n\n<p>Facebook: https:\/\/www.facebook.com\/share\/r\/1fWbFHUCyp\/?mibextid=wwXIfr<\/p>\n\n\n\n<p>X: https:\/\/x.com\/anacmx_\/status\/2077144379463025058?s=46<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Monterrey, NL El presidente de la Asociaci\u00f3n Nacional de Alcaldes (ANAC M\u00e9xico) y tambi\u00e9n alcalde de Miguel Hidalgo, en la Ciudad de M\u00e9xico, Mauricio Tabe Echartea, se sum\u00f3 al pedido de 18 de sus hom\u00f3logos en esta entidad, para que se transfieran m\u00e1s de mil 700 millones de pesos que se adeudan a los municipios. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":42034,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[15,6],"tags":[],"class_list":["post-42033","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-relevante","category-local"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Monterrey, NL El presidente de la Asociaci\u00f3n Nacional de Alcaldes (ANAC M\u00e9xico) y tambi\u00e9n alcalde de Miguel Hidalgo, en la Ciudad de M\u00e9xico, Mauricio Tabe Echartea, se sum\u00f3 al pedido de 18 de sus hom\u00f3logos en esta entidad, para que se transfieran m\u00e1s de mil 700 millones de pesos que se adeudan a los municipios.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"digitalreportmx.com\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/14\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_MX\" \/>\n\t\t<meta property=\"og:site_name\" content=\"-\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"ANAC se une al reclamo: exigen dinero a Nuevo Le\u00f3n -\" \/>\n\t\t<meta property=\"og:description\" content=\"Monterrey, NL El presidente de la Asociaci\u00f3n Nacional de Alcaldes (ANAC M\u00e9xico) y tambi\u00e9n alcalde de Miguel Hidalgo, en la Ciudad de M\u00e9xico, Mauricio Tabe Echartea, se sum\u00f3 al pedido de 18 de sus hom\u00f3logos en esta entidad, para que se transfieran m\u00e1s de mil 700 millones de pesos que se adeudan a los municipios.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/14\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/digitalreportmx.com\/wp-content\/uploads\/2024\/02\/cropped-cropped-DRLOGO-1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/digitalreportmx.com\/wp-content\/uploads\/2024\/02\/cropped-cropped-DRLOGO-1.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-07-15T01:38:07+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-15T01:38:08+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"ANAC se une al reclamo: exigen dinero a Nuevo Le\u00f3n -\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Monterrey, NL El presidente de la Asociaci\u00f3n Nacional de Alcaldes (ANAC M\u00e9xico) y tambi\u00e9n alcalde de Miguel Hidalgo, en la Ciudad de M\u00e9xico, Mauricio Tabe Echartea, se sum\u00f3 al pedido de 18 de sus hom\u00f3logos en esta entidad, para que se transfieran m\u00e1s de mil 700 millones de pesos que se adeudan a los municipios.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/digitalreportmx.com\/wp-content\/uploads\/2024\/02\/cropped-cropped-DRLOGO-1.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/2026\\\/07\\\/14\\\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\\\/#blogposting\",\"name\":\"ANAC se une al reclamo: exigen dinero a Nuevo Le\\u00f3n -\",\"headline\":\"ANAC se une al reclamo: exigen dinero a Nuevo Le\\u00f3n\",\"author\":{\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/author\\\/digitalreportmx-com\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/digitalreportmx.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/IMG-20260713-WA0114-1.jpg\",\"width\":1280,\"height\":854},\"datePublished\":\"2026-07-14T19:38:07-06:00\",\"dateModified\":\"2026-07-14T19:38:08-06:00\",\"inLanguage\":\"es-MX\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/2026\\\/07\\\/14\\\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/2026\\\/07\\\/14\\\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\\\/#webpage\"},\"articleSection\":\"-Relevante, Local\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/2026\\\/07\\\/14\\\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/digitalreportmx.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/digitalreportmx.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/category\\\/local\\\/#listItem\",\"name\":\"Local\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/category\\\/local\\\/#listItem\",\"position\":2,\"name\":\"Local\",\"item\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/category\\\/local\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/2026\\\/07\\\/14\\\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\\\/#listItem\",\"name\":\"ANAC se une al reclamo: exigen dinero a Nuevo Le\\u00f3n\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/digitalreportmx.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/2026\\\/07\\\/14\\\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\\\/#listItem\",\"position\":3,\"name\":\"ANAC se une al reclamo: exigen dinero a Nuevo Le\\u00f3n\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/category\\\/local\\\/#listItem\",\"name\":\"Local\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/#organization\",\"name\":\"digitalreportmx.com\",\"url\":\"https:\\\/\\\/digitalreportmx.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/digitalreportmx.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-cropped-DRLOGO-1.jpg\",\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/2026\\\/07\\\/14\\\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\\\/#organizationLogo\",\"width\":1693,\"height\":281},\"image\":{\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/2026\\\/07\\\/14\\\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/author\\\/digitalreportmx-com\\\/#author\",\"url\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/author\\\/digitalreportmx-com\\\/\",\"name\":\"digitalreportmx.com\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/2026\\\/07\\\/14\\\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2188078a0605d73ef57c1a9ac85e5a46c94d745432f7d01a9f4feac443943526?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"digitalreportmx.com\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/2026\\\/07\\\/14\\\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\\\/#webpage\",\"url\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/2026\\\/07\\\/14\\\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\\\/\",\"name\":\"ANAC se une al reclamo: exigen dinero a Nuevo Le\\u00f3n -\",\"description\":\"Monterrey, NL El presidente de la Asociaci\\u00f3n Nacional de Alcaldes (ANAC M\\u00e9xico) y tambi\\u00e9n alcalde de Miguel Hidalgo, en la Ciudad de M\\u00e9xico, Mauricio Tabe Echartea, se sum\\u00f3 al pedido de 18 de sus hom\\u00f3logos en esta entidad, para que se transfieran m\\u00e1s de mil 700 millones de pesos que se adeudan a los municipios.\",\"inLanguage\":\"es-MX\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/2026\\\/07\\\/14\\\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/author\\\/digitalreportmx-com\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/author\\\/digitalreportmx-com\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/digitalreportmx.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/IMG-20260713-WA0114-1.jpg\",\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/2026\\\/07\\\/14\\\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\\\/#mainImage\",\"width\":1280,\"height\":854},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/2026\\\/07\\\/14\\\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\\\/#mainImage\"},\"datePublished\":\"2026-07-14T19:38:07-06:00\",\"dateModified\":\"2026-07-14T19:38:08-06:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/#website\",\"url\":\"https:\\\/\\\/digitalreportmx.com\\\/\",\"name\":\"digitalreportmx.com\",\"inLanguage\":\"es-MX\",\"publisher\":{\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"ANAC se une al reclamo: exigen dinero a Nuevo Le\u00f3n -","description":"Monterrey, NL El presidente de la Asociaci\u00f3n Nacional de Alcaldes (ANAC M\u00e9xico) y tambi\u00e9n alcalde de Miguel Hidalgo, en la Ciudad de M\u00e9xico, Mauricio Tabe Echartea, se sum\u00f3 al pedido de 18 de sus hom\u00f3logos en esta entidad, para que se transfieran m\u00e1s de mil 700 millones de pesos que se adeudan a los municipios.","canonical_url":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/14\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/14\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\/#blogposting","name":"ANAC se une al reclamo: exigen dinero a Nuevo Le\u00f3n -","headline":"ANAC se une al reclamo: exigen dinero a Nuevo Le\u00f3n","author":{"@id":"https:\/\/digitalreportmx.com\/index.php\/author\/digitalreportmx-com\/#author"},"publisher":{"@id":"https:\/\/digitalreportmx.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/digitalreportmx.com\/wp-content\/uploads\/2026\/07\/IMG-20260713-WA0114-1.jpg","width":1280,"height":854},"datePublished":"2026-07-14T19:38:07-06:00","dateModified":"2026-07-14T19:38:08-06:00","inLanguage":"es-MX","mainEntityOfPage":{"@id":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/14\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\/#webpage"},"isPartOf":{"@id":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/14\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\/#webpage"},"articleSection":"-Relevante, Local"},{"@type":"BreadcrumbList","@id":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/14\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/digitalreportmx.com#listItem","position":1,"name":"Home","item":"https:\/\/digitalreportmx.com","nextItem":{"@type":"ListItem","@id":"https:\/\/digitalreportmx.com\/index.php\/category\/local\/#listItem","name":"Local"}},{"@type":"ListItem","@id":"https:\/\/digitalreportmx.com\/index.php\/category\/local\/#listItem","position":2,"name":"Local","item":"https:\/\/digitalreportmx.com\/index.php\/category\/local\/","nextItem":{"@type":"ListItem","@id":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/14\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\/#listItem","name":"ANAC se une al reclamo: exigen dinero a Nuevo Le\u00f3n"},"previousItem":{"@type":"ListItem","@id":"https:\/\/digitalreportmx.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/14\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\/#listItem","position":3,"name":"ANAC se une al reclamo: exigen dinero a Nuevo Le\u00f3n","previousItem":{"@type":"ListItem","@id":"https:\/\/digitalreportmx.com\/index.php\/category\/local\/#listItem","name":"Local"}}]},{"@type":"Organization","@id":"https:\/\/digitalreportmx.com\/#organization","name":"digitalreportmx.com","url":"https:\/\/digitalreportmx.com\/","logo":{"@type":"ImageObject","url":"https:\/\/digitalreportmx.com\/wp-content\/uploads\/2024\/02\/cropped-cropped-DRLOGO-1.jpg","@id":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/14\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\/#organizationLogo","width":1693,"height":281},"image":{"@id":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/14\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/digitalreportmx.com\/index.php\/author\/digitalreportmx-com\/#author","url":"https:\/\/digitalreportmx.com\/index.php\/author\/digitalreportmx-com\/","name":"digitalreportmx.com","image":{"@type":"ImageObject","@id":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/14\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/2188078a0605d73ef57c1a9ac85e5a46c94d745432f7d01a9f4feac443943526?s=96&d=mm&r=g","width":96,"height":96,"caption":"digitalreportmx.com"}},{"@type":"WebPage","@id":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/14\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\/#webpage","url":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/14\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\/","name":"ANAC se une al reclamo: exigen dinero a Nuevo Le\u00f3n -","description":"Monterrey, NL El presidente de la Asociaci\u00f3n Nacional de Alcaldes (ANAC M\u00e9xico) y tambi\u00e9n alcalde de Miguel Hidalgo, en la Ciudad de M\u00e9xico, Mauricio Tabe Echartea, se sum\u00f3 al pedido de 18 de sus hom\u00f3logos en esta entidad, para que se transfieran m\u00e1s de mil 700 millones de pesos que se adeudan a los municipios.","inLanguage":"es-MX","isPartOf":{"@id":"https:\/\/digitalreportmx.com\/#website"},"breadcrumb":{"@id":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/14\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\/#breadcrumblist"},"author":{"@id":"https:\/\/digitalreportmx.com\/index.php\/author\/digitalreportmx-com\/#author"},"creator":{"@id":"https:\/\/digitalreportmx.com\/index.php\/author\/digitalreportmx-com\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/digitalreportmx.com\/wp-content\/uploads\/2026\/07\/IMG-20260713-WA0114-1.jpg","@id":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/14\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\/#mainImage","width":1280,"height":854},"primaryImageOfPage":{"@id":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/14\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\/#mainImage"},"datePublished":"2026-07-14T19:38:07-06:00","dateModified":"2026-07-14T19:38:08-06:00"},{"@type":"WebSite","@id":"https:\/\/digitalreportmx.com\/#website","url":"https:\/\/digitalreportmx.com\/","name":"digitalreportmx.com","inLanguage":"es-MX","publisher":{"@id":"https:\/\/digitalreportmx.com\/#organization"}}]},"og:locale":"es_MX","og:site_name":"-","og:type":"article","og:title":"ANAC se une al reclamo: exigen dinero a Nuevo Le\u00f3n -","og:description":"Monterrey, NL El presidente de la Asociaci\u00f3n Nacional de Alcaldes (ANAC M\u00e9xico) y tambi\u00e9n alcalde de Miguel Hidalgo, en la Ciudad de M\u00e9xico, Mauricio Tabe Echartea, se sum\u00f3 al pedido de 18 de sus hom\u00f3logos en esta entidad, para que se transfieran m\u00e1s de mil 700 millones de pesos que se adeudan a los municipios.","og:url":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/14\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\/","og:image":"https:\/\/digitalreportmx.com\/wp-content\/uploads\/2024\/02\/cropped-cropped-DRLOGO-1.jpg","og:image:secure_url":"https:\/\/digitalreportmx.com\/wp-content\/uploads\/2024\/02\/cropped-cropped-DRLOGO-1.jpg","article:published_time":"2026-07-15T01:38:07+00:00","article:modified_time":"2026-07-15T01:38:08+00:00","twitter:card":"summary_large_image","twitter:title":"ANAC se une al reclamo: exigen dinero a Nuevo Le\u00f3n -","twitter:description":"Monterrey, NL El presidente de la Asociaci\u00f3n Nacional de Alcaldes (ANAC M\u00e9xico) y tambi\u00e9n alcalde de Miguel Hidalgo, en la Ciudad de M\u00e9xico, Mauricio Tabe Echartea, se sum\u00f3 al pedido de 18 de sus hom\u00f3logos en esta entidad, para que se transfieran m\u00e1s de mil 700 millones de pesos que se adeudan a los municipios.","twitter:image":"https:\/\/digitalreportmx.com\/wp-content\/uploads\/2024\/02\/cropped-cropped-DRLOGO-1.jpg"},"aioseo_meta_data":{"post_id":"42033","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":{"subject":"","preview":"","content":""},"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-07-15 01:38:08","updated":"2026-07-15 01:38:56","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/digitalreportmx.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/digitalreportmx.com\/index.php\/category\/local\/\" title=\"Local\">Local<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tANAC se une al reclamo: exigen dinero a Nuevo Le\u00f3n\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/digitalreportmx.com"},{"label":"Local","link":"https:\/\/digitalreportmx.com\/index.php\/category\/local\/"},{"label":"ANAC se une al reclamo: exigen dinero a Nuevo Le\u00f3n","link":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/14\/anac-se-une-al-reclamo-exigen-dinero-a-nuevo-leon\/"}],"_links":{"self":[{"href":"https:\/\/digitalreportmx.com\/index.php\/wp-json\/wp\/v2\/posts\/42033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digitalreportmx.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/digitalreportmx.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/digitalreportmx.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/digitalreportmx.com\/index.php\/wp-json\/wp\/v2\/comments?post=42033"}],"version-history":[{"count":1,"href":"https:\/\/digitalreportmx.com\/index.php\/wp-json\/wp\/v2\/posts\/42033\/revisions"}],"predecessor-version":[{"id":42035,"href":"https:\/\/digitalreportmx.com\/index.php\/wp-json\/wp\/v2\/posts\/42033\/revisions\/42035"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/digitalreportmx.com\/index.php\/wp-json\/wp\/v2\/media\/42034"}],"wp:attachment":[{"href":"https:\/\/digitalreportmx.com\/index.php\/wp-json\/wp\/v2\/media?parent=42033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/digitalreportmx.com\/index.php\/wp-json\/wp\/v2\/categories?post=42033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/digitalreportmx.com\/index.php\/wp-json\/wp\/v2\/tags?post=42033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}