{"id":42095,"date":"2026-07-15T15:05:46","date_gmt":"2026-07-15T21:05:46","guid":{"rendered":"https:\/\/digitalreportmx.com\/?p=42095"},"modified":"2026-07-15T15:05:46","modified_gmt":"2026-07-15T21:05:46","slug":"guadalupe-proyecta-nuevo-pulmon-urbano","status":"publish","type":"post","link":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/15\/guadalupe-proyecta-nuevo-pulmon-urbano\/","title":{"rendered":"Guadalupe proyecta nuevo pulm\u00f3n urbano"},"content":{"rendered":"\n<p><kbd>Guadalupe, NL <\/kbd><\/p>\n\n\n\n<p>El Gobierno de Guadalupe utilizar\u00e1 todos los recursos legales a su alcance para rescatar las instalaciones de la f\u00e1brica REMOSA, ubicada en la Colonia El Sabino.<\/p>\n\n\n\n<p><br>Este mi\u00e9rcoles en Sesi\u00f3n de Cabildo, el Alcalde H\u00e9ctor Garc\u00eda solicit\u00f3 a los integrantes del Ayuntamiento respaldar una estrategia para localizar al due\u00f1o del predio y exhortarlo a poner en orden el sitio o en su defecto iniciar las acciones legales pertinentes para devolver la tranquilidad a los vecinos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/digitalreportmx.com\/wp-content\/uploads\/2026\/07\/1000280141-1024x683.jpg\" alt=\"\" class=\"wp-image-42096\" srcset=\"https:\/\/digitalreportmx.com\/wp-content\/uploads\/2026\/07\/1000280141-1024x683.jpg 1024w, https:\/\/digitalreportmx.com\/wp-content\/uploads\/2026\/07\/1000280141-300x200.jpg 300w, https:\/\/digitalreportmx.com\/wp-content\/uploads\/2026\/07\/1000280141-768x512.jpg 768w, https:\/\/digitalreportmx.com\/wp-content\/uploads\/2026\/07\/1000280141.jpg 1344w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><br>\u201cCreo que Guadalupe ya no merece este tipo de abandono de propiedades, privadas o p\u00fablicas, \u00e9sta, aparentemente es una propiedad privada que necesitamos intervenirla, es decir, queremos hacer el llamado a quien sea el propietario o propietarios para que pongan en orden esto, porque all\u00ed habitan cientos de familias alrededor de ese lugar y no solo los pone en riesgo de seguridad sino tambi\u00e9n de insalubridad\u201d, expres\u00f3 el mun\u00edcipe.<\/p>\n\n\n\n<p><br>A consecuencia del abandono del inmueble son m\u00faltiples las quejas de insalubridad, inseguridad y otras molestias de vecinos por lo que espera rescatar ese predio y convertirlo en un \u00e1rea verde.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/digitalreportmx.com\/wp-content\/uploads\/2026\/07\/1000280133-1024x682.jpg\" alt=\"\" class=\"wp-image-42097\" srcset=\"https:\/\/digitalreportmx.com\/wp-content\/uploads\/2026\/07\/1000280133-1024x682.jpg 1024w, https:\/\/digitalreportmx.com\/wp-content\/uploads\/2026\/07\/1000280133-300x200.jpg 300w, https:\/\/digitalreportmx.com\/wp-content\/uploads\/2026\/07\/1000280133-768x512.jpg 768w, https:\/\/digitalreportmx.com\/wp-content\/uploads\/2026\/07\/1000280133-1536x1023.jpg 1536w, https:\/\/digitalreportmx.com\/wp-content\/uploads\/2026\/07\/1000280133.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><br>Precis\u00f3 que la Polic\u00eda de Guadalupe mantiene recorridos de vigilancia en este sector y ha detenido a personas por faltas administrativas como parte de las acciones permanentes para prevenir delitos en el sitio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Guadalupe, NL El Gobierno de Guadalupe utilizar\u00e1 todos los recursos legales a su alcance para rescatar las instalaciones de la f\u00e1brica REMOSA, ubicada en la Colonia El Sabino. Este mi\u00e9rcoles en Sesi\u00f3n de Cabildo, el Alcalde H\u00e9ctor Garc\u00eda solicit\u00f3 a los integrantes del Ayuntamiento respaldar una estrategia para localizar al due\u00f1o del predio y exhortarlo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":42098,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[15,6],"tags":[],"class_list":["post-42095","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-relevante","category-local"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Guadalupe, NL El Gobierno de Guadalupe utilizar\u00e1 todos los recursos legales a su alcance para rescatar las instalaciones de la f\u00e1brica REMOSA, ubicada en la Colonia El Sabino. Este mi\u00e9rcoles en Sesi\u00f3n de Cabildo, el Alcalde H\u00e9ctor Garc\u00eda solicit\u00f3 a los integrantes del Ayuntamiento respaldar una estrategia para localizar al due\u00f1o del predio y exhortarlo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"digitalreportmx.com\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/15\/guadalupe-proyecta-nuevo-pulmon-urbano\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_MX\" \/>\n\t\t<meta property=\"og:site_name\" content=\"-\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Guadalupe proyecta nuevo pulm\u00f3n urbano -\" \/>\n\t\t<meta property=\"og:description\" content=\"Guadalupe, NL El Gobierno de Guadalupe utilizar\u00e1 todos los recursos legales a su alcance para rescatar las instalaciones de la f\u00e1brica REMOSA, ubicada en la Colonia El Sabino. Este mi\u00e9rcoles en Sesi\u00f3n de Cabildo, el Alcalde H\u00e9ctor Garc\u00eda solicit\u00f3 a los integrantes del Ayuntamiento respaldar una estrategia para localizar al due\u00f1o del predio y exhortarlo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/15\/guadalupe-proyecta-nuevo-pulmon-urbano\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/digitalreportmx.com\/wp-content\/uploads\/2024\/02\/cropped-cropped-DRLOGO-1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/digitalreportmx.com\/wp-content\/uploads\/2024\/02\/cropped-cropped-DRLOGO-1.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-07-15T21:05:46+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-15T21:05:46+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Guadalupe proyecta nuevo pulm\u00f3n urbano -\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Guadalupe, NL El Gobierno de Guadalupe utilizar\u00e1 todos los recursos legales a su alcance para rescatar las instalaciones de la f\u00e1brica REMOSA, ubicada en la Colonia El Sabino. Este mi\u00e9rcoles en Sesi\u00f3n de Cabildo, el Alcalde H\u00e9ctor Garc\u00eda solicit\u00f3 a los integrantes del Ayuntamiento respaldar una estrategia para localizar al due\u00f1o del predio y exhortarlo\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/digitalreportmx.com\/wp-content\/uploads\/2024\/02\/cropped-cropped-DRLOGO-1.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/2026\\\/07\\\/15\\\/guadalupe-proyecta-nuevo-pulmon-urbano\\\/#blogposting\",\"name\":\"Guadalupe proyecta nuevo pulm\\u00f3n urbano -\",\"headline\":\"Guadalupe proyecta nuevo pulm\\u00f3n urbano\",\"author\":{\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/author\\\/digitalreportmx-com\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/digitalreportmx.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/IMG-20260715-WA0067.jpg\",\"width\":1500,\"height\":1000},\"datePublished\":\"2026-07-15T15:05:46-06:00\",\"dateModified\":\"2026-07-15T15:05:46-06:00\",\"inLanguage\":\"es-MX\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/2026\\\/07\\\/15\\\/guadalupe-proyecta-nuevo-pulmon-urbano\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/2026\\\/07\\\/15\\\/guadalupe-proyecta-nuevo-pulmon-urbano\\\/#webpage\"},\"articleSection\":\"-Relevante, Local\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/2026\\\/07\\\/15\\\/guadalupe-proyecta-nuevo-pulmon-urbano\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/digitalreportmx.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/digitalreportmx.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/category\\\/local\\\/#listItem\",\"name\":\"Local\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/category\\\/local\\\/#listItem\",\"position\":2,\"name\":\"Local\",\"item\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/category\\\/local\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/2026\\\/07\\\/15\\\/guadalupe-proyecta-nuevo-pulmon-urbano\\\/#listItem\",\"name\":\"Guadalupe proyecta nuevo pulm\\u00f3n urbano\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/digitalreportmx.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/2026\\\/07\\\/15\\\/guadalupe-proyecta-nuevo-pulmon-urbano\\\/#listItem\",\"position\":3,\"name\":\"Guadalupe proyecta nuevo pulm\\u00f3n urbano\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/category\\\/local\\\/#listItem\",\"name\":\"Local\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/#organization\",\"name\":\"digitalreportmx.com\",\"url\":\"https:\\\/\\\/digitalreportmx.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/digitalreportmx.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-cropped-DRLOGO-1.jpg\",\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/2026\\\/07\\\/15\\\/guadalupe-proyecta-nuevo-pulmon-urbano\\\/#organizationLogo\",\"width\":1693,\"height\":281},\"image\":{\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/2026\\\/07\\\/15\\\/guadalupe-proyecta-nuevo-pulmon-urbano\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/author\\\/digitalreportmx-com\\\/#author\",\"url\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/author\\\/digitalreportmx-com\\\/\",\"name\":\"digitalreportmx.com\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/2026\\\/07\\\/15\\\/guadalupe-proyecta-nuevo-pulmon-urbano\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2188078a0605d73ef57c1a9ac85e5a46c94d745432f7d01a9f4feac443943526?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"digitalreportmx.com\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/2026\\\/07\\\/15\\\/guadalupe-proyecta-nuevo-pulmon-urbano\\\/#webpage\",\"url\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/2026\\\/07\\\/15\\\/guadalupe-proyecta-nuevo-pulmon-urbano\\\/\",\"name\":\"Guadalupe proyecta nuevo pulm\\u00f3n urbano -\",\"description\":\"Guadalupe, NL El Gobierno de Guadalupe utilizar\\u00e1 todos los recursos legales a su alcance para rescatar las instalaciones de la f\\u00e1brica REMOSA, ubicada en la Colonia El Sabino. Este mi\\u00e9rcoles en Sesi\\u00f3n de Cabildo, el Alcalde H\\u00e9ctor Garc\\u00eda solicit\\u00f3 a los integrantes del Ayuntamiento respaldar una estrategia para localizar al due\\u00f1o del predio y exhortarlo\",\"inLanguage\":\"es-MX\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/2026\\\/07\\\/15\\\/guadalupe-proyecta-nuevo-pulmon-urbano\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/author\\\/digitalreportmx-com\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/author\\\/digitalreportmx-com\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/digitalreportmx.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/IMG-20260715-WA0067.jpg\",\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/2026\\\/07\\\/15\\\/guadalupe-proyecta-nuevo-pulmon-urbano\\\/#mainImage\",\"width\":1500,\"height\":1000},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/index.php\\\/2026\\\/07\\\/15\\\/guadalupe-proyecta-nuevo-pulmon-urbano\\\/#mainImage\"},\"datePublished\":\"2026-07-15T15:05:46-06:00\",\"dateModified\":\"2026-07-15T15:05:46-06:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/#website\",\"url\":\"https:\\\/\\\/digitalreportmx.com\\\/\",\"name\":\"digitalreportmx.com\",\"inLanguage\":\"es-MX\",\"publisher\":{\"@id\":\"https:\\\/\\\/digitalreportmx.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Guadalupe proyecta nuevo pulm\u00f3n urbano -","description":"Guadalupe, NL El Gobierno de Guadalupe utilizar\u00e1 todos los recursos legales a su alcance para rescatar las instalaciones de la f\u00e1brica REMOSA, ubicada en la Colonia El Sabino. Este mi\u00e9rcoles en Sesi\u00f3n de Cabildo, el Alcalde H\u00e9ctor Garc\u00eda solicit\u00f3 a los integrantes del Ayuntamiento respaldar una estrategia para localizar al due\u00f1o del predio y exhortarlo","canonical_url":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/15\/guadalupe-proyecta-nuevo-pulmon-urbano\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/15\/guadalupe-proyecta-nuevo-pulmon-urbano\/#blogposting","name":"Guadalupe proyecta nuevo pulm\u00f3n urbano -","headline":"Guadalupe proyecta nuevo pulm\u00f3n urbano","author":{"@id":"https:\/\/digitalreportmx.com\/index.php\/author\/digitalreportmx-com\/#author"},"publisher":{"@id":"https:\/\/digitalreportmx.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/digitalreportmx.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0067.jpg","width":1500,"height":1000},"datePublished":"2026-07-15T15:05:46-06:00","dateModified":"2026-07-15T15:05:46-06:00","inLanguage":"es-MX","mainEntityOfPage":{"@id":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/15\/guadalupe-proyecta-nuevo-pulmon-urbano\/#webpage"},"isPartOf":{"@id":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/15\/guadalupe-proyecta-nuevo-pulmon-urbano\/#webpage"},"articleSection":"-Relevante, Local"},{"@type":"BreadcrumbList","@id":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/15\/guadalupe-proyecta-nuevo-pulmon-urbano\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/digitalreportmx.com#listItem","position":1,"name":"Home","item":"https:\/\/digitalreportmx.com","nextItem":{"@type":"ListItem","@id":"https:\/\/digitalreportmx.com\/index.php\/category\/local\/#listItem","name":"Local"}},{"@type":"ListItem","@id":"https:\/\/digitalreportmx.com\/index.php\/category\/local\/#listItem","position":2,"name":"Local","item":"https:\/\/digitalreportmx.com\/index.php\/category\/local\/","nextItem":{"@type":"ListItem","@id":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/15\/guadalupe-proyecta-nuevo-pulmon-urbano\/#listItem","name":"Guadalupe proyecta nuevo pulm\u00f3n urbano"},"previousItem":{"@type":"ListItem","@id":"https:\/\/digitalreportmx.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/15\/guadalupe-proyecta-nuevo-pulmon-urbano\/#listItem","position":3,"name":"Guadalupe proyecta nuevo pulm\u00f3n urbano","previousItem":{"@type":"ListItem","@id":"https:\/\/digitalreportmx.com\/index.php\/category\/local\/#listItem","name":"Local"}}]},{"@type":"Organization","@id":"https:\/\/digitalreportmx.com\/#organization","name":"digitalreportmx.com","url":"https:\/\/digitalreportmx.com\/","logo":{"@type":"ImageObject","url":"https:\/\/digitalreportmx.com\/wp-content\/uploads\/2024\/02\/cropped-cropped-DRLOGO-1.jpg","@id":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/15\/guadalupe-proyecta-nuevo-pulmon-urbano\/#organizationLogo","width":1693,"height":281},"image":{"@id":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/15\/guadalupe-proyecta-nuevo-pulmon-urbano\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/digitalreportmx.com\/index.php\/author\/digitalreportmx-com\/#author","url":"https:\/\/digitalreportmx.com\/index.php\/author\/digitalreportmx-com\/","name":"digitalreportmx.com","image":{"@type":"ImageObject","@id":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/15\/guadalupe-proyecta-nuevo-pulmon-urbano\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/2188078a0605d73ef57c1a9ac85e5a46c94d745432f7d01a9f4feac443943526?s=96&d=mm&r=g","width":96,"height":96,"caption":"digitalreportmx.com"}},{"@type":"WebPage","@id":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/15\/guadalupe-proyecta-nuevo-pulmon-urbano\/#webpage","url":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/15\/guadalupe-proyecta-nuevo-pulmon-urbano\/","name":"Guadalupe proyecta nuevo pulm\u00f3n urbano -","description":"Guadalupe, NL El Gobierno de Guadalupe utilizar\u00e1 todos los recursos legales a su alcance para rescatar las instalaciones de la f\u00e1brica REMOSA, ubicada en la Colonia El Sabino. Este mi\u00e9rcoles en Sesi\u00f3n de Cabildo, el Alcalde H\u00e9ctor Garc\u00eda solicit\u00f3 a los integrantes del Ayuntamiento respaldar una estrategia para localizar al due\u00f1o del predio y exhortarlo","inLanguage":"es-MX","isPartOf":{"@id":"https:\/\/digitalreportmx.com\/#website"},"breadcrumb":{"@id":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/15\/guadalupe-proyecta-nuevo-pulmon-urbano\/#breadcrumblist"},"author":{"@id":"https:\/\/digitalreportmx.com\/index.php\/author\/digitalreportmx-com\/#author"},"creator":{"@id":"https:\/\/digitalreportmx.com\/index.php\/author\/digitalreportmx-com\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/digitalreportmx.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0067.jpg","@id":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/15\/guadalupe-proyecta-nuevo-pulmon-urbano\/#mainImage","width":1500,"height":1000},"primaryImageOfPage":{"@id":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/15\/guadalupe-proyecta-nuevo-pulmon-urbano\/#mainImage"},"datePublished":"2026-07-15T15:05:46-06:00","dateModified":"2026-07-15T15:05:46-06:00"},{"@type":"WebSite","@id":"https:\/\/digitalreportmx.com\/#website","url":"https:\/\/digitalreportmx.com\/","name":"digitalreportmx.com","inLanguage":"es-MX","publisher":{"@id":"https:\/\/digitalreportmx.com\/#organization"}}]},"og:locale":"es_MX","og:site_name":"-","og:type":"article","og:title":"Guadalupe proyecta nuevo pulm\u00f3n urbano -","og:description":"Guadalupe, NL El Gobierno de Guadalupe utilizar\u00e1 todos los recursos legales a su alcance para rescatar las instalaciones de la f\u00e1brica REMOSA, ubicada en la Colonia El Sabino. Este mi\u00e9rcoles en Sesi\u00f3n de Cabildo, el Alcalde H\u00e9ctor Garc\u00eda solicit\u00f3 a los integrantes del Ayuntamiento respaldar una estrategia para localizar al due\u00f1o del predio y exhortarlo","og:url":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/15\/guadalupe-proyecta-nuevo-pulmon-urbano\/","og:image":"https:\/\/digitalreportmx.com\/wp-content\/uploads\/2024\/02\/cropped-cropped-DRLOGO-1.jpg","og:image:secure_url":"https:\/\/digitalreportmx.com\/wp-content\/uploads\/2024\/02\/cropped-cropped-DRLOGO-1.jpg","article:published_time":"2026-07-15T21:05:46+00:00","article:modified_time":"2026-07-15T21:05:46+00:00","twitter:card":"summary_large_image","twitter:title":"Guadalupe proyecta nuevo pulm\u00f3n urbano -","twitter:description":"Guadalupe, NL El Gobierno de Guadalupe utilizar\u00e1 todos los recursos legales a su alcance para rescatar las instalaciones de la f\u00e1brica REMOSA, ubicada en la Colonia El Sabino. Este mi\u00e9rcoles en Sesi\u00f3n de Cabildo, el Alcalde H\u00e9ctor Garc\u00eda solicit\u00f3 a los integrantes del Ayuntamiento respaldar una estrategia para localizar al due\u00f1o del predio y exhortarlo","twitter:image":"https:\/\/digitalreportmx.com\/wp-content\/uploads\/2024\/02\/cropped-cropped-DRLOGO-1.jpg"},"aioseo_meta_data":{"post_id":"42095","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":{"subject":"","preview":"","content":""},"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-07-15 21:05:46","updated":"2026-07-15 21:06:04","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/digitalreportmx.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/digitalreportmx.com\/index.php\/category\/local\/\" title=\"Local\">Local<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tGuadalupe proyecta nuevo pulm\u00f3n urbano\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/digitalreportmx.com"},{"label":"Local","link":"https:\/\/digitalreportmx.com\/index.php\/category\/local\/"},{"label":"Guadalupe proyecta nuevo pulm\u00f3n urbano","link":"https:\/\/digitalreportmx.com\/index.php\/2026\/07\/15\/guadalupe-proyecta-nuevo-pulmon-urbano\/"}],"_links":{"self":[{"href":"https:\/\/digitalreportmx.com\/index.php\/wp-json\/wp\/v2\/posts\/42095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digitalreportmx.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/digitalreportmx.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/digitalreportmx.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/digitalreportmx.com\/index.php\/wp-json\/wp\/v2\/comments?post=42095"}],"version-history":[{"count":1,"href":"https:\/\/digitalreportmx.com\/index.php\/wp-json\/wp\/v2\/posts\/42095\/revisions"}],"predecessor-version":[{"id":42099,"href":"https:\/\/digitalreportmx.com\/index.php\/wp-json\/wp\/v2\/posts\/42095\/revisions\/42099"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/digitalreportmx.com\/index.php\/wp-json\/wp\/v2\/media\/42098"}],"wp:attachment":[{"href":"https:\/\/digitalreportmx.com\/index.php\/wp-json\/wp\/v2\/media?parent=42095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/digitalreportmx.com\/index.php\/wp-json\/wp\/v2\/categories?post=42095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/digitalreportmx.com\/index.php\/wp-json\/wp\/v2\/tags?post=42095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}